{"id":40,"count":1,"description":"","link":"https:\/\/www.speedladies.com\/en\/tag\/frauen-auf-der-rennstrecke\/","name":"Frauen auf der Rennstrecke","slug":"frauen-auf-der-rennstrecke","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tags\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/posts?tags=40"},{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tribe_events?tags=40"},{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}