{"id":253,"count":1,"description":"","link":"https:\/\/www.speedladies.com\/en\/tag\/motorradrennen-brunn\/","name":"Motorradrennen Br\u00fcnn","slug":"motorradrennen-brunn","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tags\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/posts?tags=253"},{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tribe_events?tags=253"},{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}