{"id":92,"date":"2008-09-17T22:17:51","date_gmt":"2008-09-17T20:17:51","guid":{"rendered":"http:\/\/www.speedladies.com\/?p=92"},"modified":"2009-02-16T16:15:45","modified_gmt":"2009-02-16T14:15:45","slug":"motorrad-richtiger-reifen","status":"publish","type":"post","link":"https:\/\/www.speedladies.com\/en\/2008\/motorrad-richtiger-reifen\/","title":{"rendered":"Die Qual der Wahl der richtigen Reifen"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Wer kennt das nicht?<\/strong><\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Welche Reifen sind wohl die Richtigen &#8230; f\u00fcr mein Bike und auch f\u00fcr mich (mein Fahrstil bzw. Fahrk\u00f6nnen)<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Grunds\u00e4tzlich sollte man unterscheiden, was will man denn \u00fcberhaupt:<\/strong><\/span><\/p>\n<ul>\n<li><em><strong>Stra\u00dfenfahren<\/strong><\/em><\/li>\n<li><em><strong>gr\u00f6\u00dfere Touren<\/strong><\/em><\/li>\n<li><em><strong>Ringfahren<\/strong><\/em><\/li>\n<\/ul>\n<p>Sobald diese Fragen gekl\u00e4rt sind, hat man den ersten Schritt in Richtung &#8220;richtige Reifen&#8221; bereits gemacht.<\/p>\n<p>Es gibt jede Menge Reifenhersteller. Die ich hier mit Namen nenne sollten nur Beispiele sein, die sich bereits gut bew\u00e4hrt haben und eigene Erfahrung dazu gemacht wurden.<\/p>\n<p><strong>Stra\u00dfenfahren und gr\u00f6\u00dfere Touren:<\/strong><\/p>\n<p style=\"padding-left: 30px;\">Willst du hohe Laufleistung und &#8220;nur&#8221; auf der Stra\u00dfe fahren, gibt es viele Allrounder wie zb.: Bridgestone BT21 oder auch der BT16 (3 Gummimischungen sorgen hier f\u00fcr den richtigen Grip), Michelin Pilot Road 2 oder auch der Diablo Strada von Pirelli. Erw\u00e4hnenswert ist auch der Road Attack. Er ist g\u00fcnstig und auch bereits ein Top-Reifen von Continental.<\/p>\n<p style=\"padding-left: 30px;\">Mit diesen Reifen bist du bestens auf der Stra\u00dfe versorgt. Sie bieten dir gute Sicherheit und das auch im Regen. F\u00fcr die Rennstrecke solltest du diese nicht nehmen, da die Reifen dort sehr hohen Temperaturen ausgesetzt sind und somit nicht mehr die notwendige Bodenhaftung haben (schmieren weg)<\/p>\n<p><strong>Ringfahren:<\/strong><\/p>\n<p style=\"padding-left: 30px;\">Tja, nat\u00fcrlich w\u00fcrde ich dort gleich mal Slicks empfehlen, aber nicht alle von uns haben Reifenw\u00e4rmer. Also nenne ich hier mal ein paar Beispiele die sich auch ohne Reifenw\u00e4rmer sehr gut auf der Strecke wohlf\u00fchlen. Ein sehr guter Reifen ist der Michelin Power Race (medium-soft). Er h\u00e4lt auch wirklich hei\u00dfe Asphalt Temperaturen aus. Hat auch noch eine Stra\u00dfenzulassung und ist somit ideal f\u00fcr eine Ausflug auf die Strecke. Weiters hat auch Pirelli einen extrem guten Allrounder anzubieten: den Diablo Supercorsa (SBK-WM Reifen). Bei Bridgestone finden wir den BT003 gerade bei Bikes die nicht unbedingt f\u00fcr den Ring speziell angepasst werden ideal. Auch Metzeler Racetac sollten wir hier nicht vergessen zu erw\u00e4hnen, da er vergleichbar ist mit dem Pirelli. Jedoch vorsicht bei sehr hei\u00dfen Renntagen. Das tut ihm  leider doch nicht so gut. Dunlop D209GP Racer wird im Yamaha R6 Cup eingesetzt. Und auch den Conti Race Attack m\u00f6chte ich hier unbedingt anf\u00fchren. Die Superdukes schw\u00f6ren bereits darauf. Ein echter Neuling mit viel Potential!<\/p>\n<p style=\"padding-left: 30px;\">\n<p>Solltest du mal erste Versuche auf der Rennstrecke wagen und nicht gleich einen extra Satz Reifen daf\u00fcr kaufen wollen, dann kann ich hier auch noch ein paar Empfehlungen aussprechen: Pilot Power Race (Medium) von Michelin, von Pirelli Dragon Supercorsa Pro SC3 und weiters den BT002 Racing Street von Bridgestone. Es w\u00fcrde dann noch den Qualifier RR von Dunlop geben, jedoch sind hier meine Erfahrungen dazu nicht die Besten.<\/p>\n<p>Detailinformation zu den angef\u00fchrten Reifen erh\u00e4lst du im Internet unter den Reifenhersteller oder auch beim Fachhandel. Vergi\u00df nie dort vorher bekannt zu geben, wohin du mit dem Reifen ziehen willst. Gerade der Fachhandel hat sehr viele Informationen und auch Erfahrungen zu bestimmten Reifen.<\/p>\n<p><span style=\"color: #0000ff;\">M\u00f6chtest du noch mehr dazu wissen, da schau einfach ins Forum. Dort werden immer aktuelle Erfahrungsberichte untereinander ausgetauscht.<\/span><\/p>\n<p style=\"padding-left: 30px;\">\n<p style=\"padding-left: 30px;\">\n","protected":false},"excerpt":{"rendered":"<p>Wer kennt das nicht? Welche Reifen sind wohl die Richtigen &#8230; f\u00fcr mein Bike und auch f\u00fcr mich (mein Fahrstil<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[26,264],"class_list":["post-92","post","type-post","status-publish","format-standard","hentry","category-reifen","tag-frauen","tag-reifen"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":0,"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.speedladies.com\/en\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}